{"id":214654,"date":"2021-11-04T13:29:42","date_gmt":"2021-11-04T12:29:42","guid":{"rendered":"https:\/\/diableries.space\/musique-et-neige\/?post_type=project&#038;p=214654"},"modified":"2026-01-06T14:39:54","modified_gmt":"2026-01-06T13:39:54","slug":"galerie-2001","status":"publish","type":"project","link":"https:\/\/www.musique-et-neige.ch\/en\/project\/galerie-2001\/","title":{"rendered":"Gallery - 2001"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; fullwidth=\u00a0\u00bbon\u00a0\u00bb next_background_color=\u00a0\u00bb#ffffff\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#31A9DE\u00a0\u00bb background_color_gradient_direction=\u00a0\u00bb360deg\u00a0\u00bb background_enable_image=\u00a0\u00bboff\u00a0\u00bb min_height=\u00a0\u00bb300px\u00a0\u00bb bottom_divider_style=\u00a0\u00bbwave2&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_fullwidth_post_title meta=\u00a0\u00bboff\u00a0\u00bb featured_image=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb title_font=\u00a0\u00bb|600||on|||||\u00a0\u00bb title_text_align=\u00a0\u00bbcenter\u00a0\u00bb title_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb title_font_size=\u00a0\u00bb36px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_fullwidth_post_title][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb custom_padding=\u00a0\u00bb0px||2px|||\u00a0\u00bb bottom_divider_style=\u00a0\u00bbwave\u00a0\u00bb bottom_divider_color=\u00a0\u00bb#4D555F\u00a0\u00bb custom_css_main_element=\u00a0\u00bbmin-height:50vh;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][dsm_masonry_gallery _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; sticky_enabled=\u00a0\u00bb0&Prime; gallery_ids=\u00a0\u00bb214658,214657,214656&Prime; custom_margin=\u00a0\u00bb||65px|||\u00a0\u00bb custom_padding=\u00a0\u00bb||136px|||\u00a0\u00bb][\/dsm_masonry_gallery][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"et_pb_module dsm_masonry_gallery dsm_masonry_gallery_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"dsm-gallery grid\" data-lightbox=\"false\" data-horizontalorder=\"true\">\n                <div class=\"grid-sizer\"><\/div><div class=\"gutter-sizer\"><\/div><div class=\"grid-item\">\n                    <div class=\"et_pb_image_wrap\">\n                        <img decoding=\"async\" src=\"https:\/\/www.musique-et-neige.ch\/wp-content\/uploads\/42_6c0f7c60.jpg\" title=\"42_6c0f7c60\" alt=\"\" class=\"dsm-skip-lazyload\" srcset=\"https:\/\/www.musique-et-neige.ch\/wp-content\/uploads\/42_6c0f7c60.jpg 640w, https:\/\/www.musique-et-neige.ch\/wp-content\/uploads\/42_6c0f7c60-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 640px, 100vw\" width=\"640\" height=\"480\" \/>\n                        \n                    <\/div>\n                <\/div><div class=\"grid-item\">\n                    <div class=\"et_pb_image_wrap\">\n                        <img decoding=\"async\" src=\"https:\/\/www.musique-et-neige.ch\/wp-content\/uploads\/43_f8a7a4f7.jpg\" title=\"43_f8a7a4f7\" alt=\"\" class=\"dsm-skip-lazyload\" srcset=\"https:\/\/www.musique-et-neige.ch\/wp-content\/uploads\/43_f8a7a4f7.jpg 640w, https:\/\/www.musique-et-neige.ch\/wp-content\/uploads\/43_f8a7a4f7-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 640px, 100vw\" width=\"640\" height=\"480\" \/>\n                        \n                    <\/div>\n                <\/div><div class=\"grid-item\">\n                    <div class=\"et_pb_image_wrap\">\n                        <img decoding=\"async\" src=\"https:\/\/www.musique-et-neige.ch\/wp-content\/uploads\/44_d32c0bbc.jpg\" title=\"44_d32c0bbc\" alt=\"\" class=\"dsm-skip-lazyload\" srcset=\"https:\/\/www.musique-et-neige.ch\/wp-content\/uploads\/44_d32c0bbc.jpg 640w, https:\/\/www.musique-et-neige.ch\/wp-content\/uploads\/44_d32c0bbc-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 640px, 100vw\" width=\"640\" height=\"480\" \/>\n                        \n                    <\/div>\n                <\/div>\n             <\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>","protected":false},"author":1,"featured_media":214658,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"project_category":[],"project_tag":[],"class_list":["post-214654","project","type-project","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.1.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Galerie - 2001 - Festival Musique &amp; Neige<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.musique-et-neige.ch\/en\/project\/galerie-2001\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Galerie - 2001\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.musique-et-neige.ch\/en\/wp-json\/wp\/v2\/project\/214654\" \/>\n<meta property=\"og:site_name\" content=\"Festival Musique &amp; Neige\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FestivalMusiqueNeige\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-06T13:39:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.musique-et-neige.ch\/wp-content\/uploads\/44_d32c0bbc.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.musique-et-neige.ch\/project\/galerie-2001\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.musique-et-neige.ch\/project\/galerie-2001\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/www.musique-et-neige.ch\/#\/schema\/person\/db2eb97a2dbeee26becb54659778a71d\"},\"headline\":\"Galerie &#8211; 2001\",\"datePublished\":\"2021-11-04T12:29:42+00:00\",\"dateModified\":\"2026-01-06T13:39:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.musique-et-neige.ch\/project\/galerie-2001\/\"},\"wordCount\":170,\"publisher\":{\"@id\":\"https:\/\/www.musique-et-neige.ch\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.musique-et-neige.ch\/project\/galerie-2001\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.musique-et-neige.ch\/wp-content\/uploads\/44_d32c0bbc.jpg\",\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.musique-et-neige.ch\/project\/galerie-2001\/\",\"url\":\"https:\/\/www.musique-et-neige.ch\/project\/galerie-2001\/\",\"name\":\"Galerie - 2001 - Festival Musique &amp; Neige\",\"isPartOf\":{\"@id\":\"https:\/\/www.musique-et-neige.ch\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.musique-et-neige.ch\/project\/galerie-2001\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.musique-et-neige.ch\/project\/galerie-2001\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.musique-et-neige.ch\/wp-content\/uploads\/44_d32c0bbc.jpg\",\"datePublished\":\"2021-11-04T12:29:42+00:00\",\"dateModified\":\"2026-01-06T13:39:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.musique-et-neige.ch\/project\/galerie-2001\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.musique-et-neige.ch\/project\/galerie-2001\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.musique-et-neige.ch\/project\/galerie-2001\/#primaryimage\",\"url\":\"https:\/\/www.musique-et-neige.ch\/wp-content\/uploads\/44_d32c0bbc.jpg\",\"contentUrl\":\"https:\/\/www.musique-et-neige.ch\/wp-content\/uploads\/44_d32c0bbc.jpg\",\"width\":640,\"height\":480,\"caption\":\"2001\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.musique-et-neige.ch\/project\/galerie-2001\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.musique-et-neige.ch\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projets\",\"item\":\"https:\/\/www.musique-et-neige.ch\/project\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Galerie &#8211; 2001\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.musique-et-neige.ch\/#website\",\"url\":\"https:\/\/www.musique-et-neige.ch\/\",\"name\":\"Festival Musique & Neige\",\"description\":\"Quand la musique de chambre enchante la montagne\",\"publisher\":{\"@id\":\"https:\/\/www.musique-et-neige.ch\/#organization\"},\"alternateName\":\"Musique & Neige\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.musique-et-neige.ch\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.musique-et-neige.ch\/#organization\",\"name\":\"Festival Musique & Neige Les Diablerets\",\"alternateName\":\"Musique & Neige\",\"url\":\"https:\/\/www.musique-et-neige.ch\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.musique-et-neige.ch\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.musique-et-neige.ch\/wp-content\/uploads\/Musique-et-neige-logo.jpg\",\"contentUrl\":\"https:\/\/www.musique-et-neige.ch\/wp-content\/uploads\/Musique-et-neige-logo.jpg\",\"width\":254,\"height\":159,\"caption\":\"Festival Musique & Neige Les Diablerets\"},\"image\":{\"@id\":\"https:\/\/www.musique-et-neige.ch\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FestivalMusiqueNeige\",\"https:\/\/www.instagram.com\/festival_musique_et_neige\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.musique-et-neige.ch\/#\/schema\/person\/db2eb97a2dbeee26becb54659778a71d\",\"name\":\"admin\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Galerie - 2001 - Festival Musique &amp; Neige","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.musique-et-neige.ch\/en\/project\/galerie-2001\/","og_locale":"en_US","og_type":"article","og_title":"Galerie - 2001","og_url":"https:\/\/www.musique-et-neige.ch\/en\/wp-json\/wp\/v2\/project\/214654","og_site_name":"Festival Musique &amp; Neige","article_publisher":"https:\/\/www.facebook.com\/FestivalMusiqueNeige","article_modified_time":"2026-01-06T13:39:54+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/www.musique-et-neige.ch\/wp-content\/uploads\/44_d32c0bbc.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.musique-et-neige.ch\/project\/galerie-2001\/#article","isPartOf":{"@id":"https:\/\/www.musique-et-neige.ch\/project\/galerie-2001\/"},"author":{"name":"admin","@id":"https:\/\/www.musique-et-neige.ch\/#\/schema\/person\/db2eb97a2dbeee26becb54659778a71d"},"headline":"Galerie &#8211; 2001","datePublished":"2021-11-04T12:29:42+00:00","dateModified":"2026-01-06T13:39:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.musique-et-neige.ch\/project\/galerie-2001\/"},"wordCount":170,"publisher":{"@id":"https:\/\/www.musique-et-neige.ch\/#organization"},"image":{"@id":"https:\/\/www.musique-et-neige.ch\/project\/galerie-2001\/#primaryimage"},"thumbnailUrl":"https:\/\/www.musique-et-neige.ch\/wp-content\/uploads\/44_d32c0bbc.jpg","inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.musique-et-neige.ch\/project\/galerie-2001\/","url":"https:\/\/www.musique-et-neige.ch\/project\/galerie-2001\/","name":"Galerie - 2001 - Festival Musique &amp; Neige","isPartOf":{"@id":"https:\/\/www.musique-et-neige.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.musique-et-neige.ch\/project\/galerie-2001\/#primaryimage"},"image":{"@id":"https:\/\/www.musique-et-neige.ch\/project\/galerie-2001\/#primaryimage"},"thumbnailUrl":"https:\/\/www.musique-et-neige.ch\/wp-content\/uploads\/44_d32c0bbc.jpg","datePublished":"2021-11-04T12:29:42+00:00","dateModified":"2026-01-06T13:39:54+00:00","breadcrumb":{"@id":"https:\/\/www.musique-et-neige.ch\/project\/galerie-2001\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.musique-et-neige.ch\/project\/galerie-2001\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.musique-et-neige.ch\/project\/galerie-2001\/#primaryimage","url":"https:\/\/www.musique-et-neige.ch\/wp-content\/uploads\/44_d32c0bbc.jpg","contentUrl":"https:\/\/www.musique-et-neige.ch\/wp-content\/uploads\/44_d32c0bbc.jpg","width":640,"height":480,"caption":"2001"},{"@type":"BreadcrumbList","@id":"https:\/\/www.musique-et-neige.ch\/project\/galerie-2001\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.musique-et-neige.ch\/"},{"@type":"ListItem","position":2,"name":"Projets","item":"https:\/\/www.musique-et-neige.ch\/project\/"},{"@type":"ListItem","position":3,"name":"Galerie &#8211; 2001"}]},{"@type":"WebSite","@id":"https:\/\/www.musique-et-neige.ch\/#website","url":"https:\/\/www.musique-et-neige.ch\/","name":"Music &amp; Snow Festival","description":"When chamber music enchants the mountains","publisher":{"@id":"https:\/\/www.musique-et-neige.ch\/#organization"},"alternateName":"Musique & Neige","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.musique-et-neige.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.musique-et-neige.ch\/#organization","name":"Festival Musique &amp; Neige Les Diablerets","alternateName":"Musique & Neige","url":"https:\/\/www.musique-et-neige.ch\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.musique-et-neige.ch\/#\/schema\/logo\/image\/","url":"https:\/\/www.musique-et-neige.ch\/wp-content\/uploads\/Musique-et-neige-logo.jpg","contentUrl":"https:\/\/www.musique-et-neige.ch\/wp-content\/uploads\/Musique-et-neige-logo.jpg","width":254,"height":159,"caption":"Festival Musique & Neige Les Diablerets"},"image":{"@id":"https:\/\/www.musique-et-neige.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FestivalMusiqueNeige","https:\/\/www.instagram.com\/festival_musique_et_neige\/"]},{"@type":"Person","@id":"https:\/\/www.musique-et-neige.ch\/#\/schema\/person\/db2eb97a2dbeee26becb54659778a71d","name":"admin"}]}},"_links":{"self":[{"href":"https:\/\/www.musique-et-neige.ch\/en\/wp-json\/wp\/v2\/project\/214654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.musique-et-neige.ch\/en\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/www.musique-et-neige.ch\/en\/wp-json\/wp\/v2\/types\/project"}],"author":[{"embeddable":true,"href":"https:\/\/www.musique-et-neige.ch\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.musique-et-neige.ch\/en\/wp-json\/wp\/v2\/comments?post=214654"}],"version-history":[{"count":4,"href":"https:\/\/www.musique-et-neige.ch\/en\/wp-json\/wp\/v2\/project\/214654\/revisions"}],"predecessor-version":[{"id":217839,"href":"https:\/\/www.musique-et-neige.ch\/en\/wp-json\/wp\/v2\/project\/214654\/revisions\/217839"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.musique-et-neige.ch\/en\/wp-json\/wp\/v2\/media\/214658"}],"wp:attachment":[{"href":"https:\/\/www.musique-et-neige.ch\/en\/wp-json\/wp\/v2\/media?parent=214654"}],"wp:term":[{"taxonomy":"project_category","embeddable":true,"href":"https:\/\/www.musique-et-neige.ch\/en\/wp-json\/wp\/v2\/project_category?post=214654"},{"taxonomy":"project_tag","embeddable":true,"href":"https:\/\/www.musique-et-neige.ch\/en\/wp-json\/wp\/v2\/project_tag?post=214654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}